{"id":3,"date":"2019-05-18T17:55:32","date_gmt":"2019-05-18T15:55:32","guid":{"rendered":"http:\/\/faur.pro\/?page_id=3"},"modified":"2024-06-02T16:05:20","modified_gmt":"2024-06-02T14:05:20","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales"},"content":{"rendered":"\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97be8bd3f30\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97be8bd3f30\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Mentions_Legales\" >Mentions L\u00e9gales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Qui_sommes-nous\" >Qui sommes-nous\u00a0?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Utilisation_des_donnees_personnelles_collectees\" >Utilisation des donn\u00e9es personnelles collect\u00e9es<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Commentaires\" >Commentaires<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Medias\" >M\u00e9dias<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Formulaires_de_contact\" >Formulaires de contact<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Cookies\" >Cookies<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Contenu_embarque_depuis_dautres_sites\" >Contenu embarqu\u00e9 depuis d\u2019autres sites<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Statistiques_et_mesures_daudience\" >Statistiques et mesures d\u2019audience<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Utilisation_et_transmission_de_vos_donnees_personnelles\" >Utilisation et transmission de vos donn\u00e9es personnelles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Durees_de_stockage_de_vos_donnees\" >Dur\u00e9es de stockage de vos donn\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Les_droits_que_vous_avez_sur_vos_donnees\" >Les droits que vous avez sur vos donn\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Transmission_de_vos_donnees_personnelles\" >Transmission de vos donn\u00e9es personnelles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Informations_de_contact\" >Informations de contact<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Informations_supplementaires\" >Informations suppl\u00e9mentaires<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Comment_nous_protegeons_vos_donnees\" >Comment nous prot\u00e9geons vos donn\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Procedures_mises_en_oeuvre_en_cas_de_fuite_de_donnees\" >Proc\u00e9dures mises en \u0153uvre en cas de fuite de donn\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Les_services_tiers_qui_nous_transmettent_des_donnees\" >Les services tiers qui nous transmettent des donn\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Operations_de_marketing_automatise_etou_de_profilage_realisees_a_laide_des_donnees_personnelles\" >Op\u00e9rations de marketing automatis\u00e9 et\/ou de profilage r\u00e9alis\u00e9es \u00e0 l\u2019aide des donn\u00e9es personnelles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#Affichage_des_informations_liees_aux_secteurs_soumis_a_des_regulations_specifiques\" >Affichage des informations li\u00e9es aux secteurs soumis \u00e0 des r\u00e9gulations sp\u00e9cifiques<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mentions_Legales\"><\/span>Mentions L\u00e9gales<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9dition du site Internet<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le site SITE (www.faur.pro), accessible \u00e0 l\u2019adresse URL https:\/\/www.faur.pro est \u00e9dit\u00e9 par Bertrand FAUR , dont le domicile est situ\u00e9 LASSEUBE-PROPRE (0625173643, faurpro@gmail.com).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Num\u00e9ros SIRET : 48389697300052<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9daction du site Internet<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Directeur de la publication : Bertrand FAUR<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contact : 0625173643 ; cabinetfaur@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>H\u00e9bergeur du site Internet<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le site www.faur.pro est h\u00e9berg\u00e9 par OVH, SAS au capital de 10 174 560 \u20ac, <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RCS Lille M\u00e9tropole 424 761 419 00045<br>Code APE 2620Z<br>N\u00b0 TVA : FR 22 424 761 419<br>Si\u00e8ge social : 2 rue Kellermann &#8211; 59100 Roubaix &#8211; France<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Qui_sommes-nous\"><\/span>Qui sommes-nous\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019adresse de notre site Web est\u00a0: https:\/\/faur.pro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Utilisation_des_donnees_personnelles_collectees\"><\/span>Utilisation des donn\u00e9es personnelles collect\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Commentaires\"><\/span>Commentaires<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quand vous laissez un commentaire sur notre site web, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse de messagerie (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici&nbsp;: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Medias\"><\/span>M\u00e9dias<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates un utilisateur ou une utilisatrice enregistr\u00e9\u00b7e et que vous t\u00e9l\u00e9versez des images sur le site web, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les visiteurs de votre site web peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Formulaires_de_contact\"><\/span>Formulaires de contact<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cookies\"><\/span>Cookies<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse de messagerie et site web dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez un compte et que vous vous connectez sur ce site, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab&nbsp;Se souvenir de moi&nbsp;\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Contenu_embarque_depuis_dautres_sites\"><\/span>Contenu embarqu\u00e9 depuis d\u2019autres sites<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Statistiques_et_mesures_daudience\"><\/span>Statistiques et mesures d\u2019audience<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Utilisation_et_transmission_de_vos_donnees_personnelles\"><\/span>Utilisation et transmission de vos donn\u00e9es personnelles<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Durees_de_stockage_de_vos_donnees\"><\/span>Dur\u00e9es de stockage de vos donn\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les utilisateurs et utilisatrices qui s\u2019enregistrent sur notre site (si cela est possible), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les utilisateurs et utilisatrices peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur nom d\u2019utilisateur\u00b7ice). Les gestionnaires du site peuvent aussi voir et modifier ces informations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_droits_que_vous_avez_sur_vos_donnees\"><\/span>Les droits que vous avez sur vos donn\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Transmission_de_vos_donnees_personnelles\"><\/span>Transmission de vos donn\u00e9es personnelles<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Informations_de_contact\"><\/span>Informations de contact<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Informations_supplementaires\"><\/span>Informations suppl\u00e9mentaires<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comment_nous_protegeons_vos_donnees\"><\/span>Comment nous prot\u00e9geons vos donn\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Procedures_mises_en_oeuvre_en_cas_de_fuite_de_donnees\"><\/span>Proc\u00e9dures mises en \u0153uvre en cas de fuite de donn\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_services_tiers_qui_nous_transmettent_des_donnees\"><\/span>Les services tiers qui nous transmettent des donn\u00e9es<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Operations_de_marketing_automatise_etou_de_profilage_realisees_a_laide_des_donnees_personnelles\"><\/span>Op\u00e9rations de marketing automatis\u00e9 et\/ou de profilage r\u00e9alis\u00e9es \u00e0 l\u2019aide des donn\u00e9es personnelles<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Affichage_des_informations_liees_aux_secteurs_soumis_a_des_regulations_specifiques\"><\/span>Affichage des informations li\u00e9es aux secteurs soumis \u00e0 des r\u00e9gulations sp\u00e9cifiques<span class=\"ez-toc-section-end\"><\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Mentions L\u00e9gales \u00c9dition du site Internet Le site SITE (www.faur.pro), accessible \u00e0 l\u2019adresse URL https:\/\/www.faur.pro est \u00e9dit\u00e9 par Bertrand FAUR , dont le domicile est situ\u00e9 LASSEUBE-PROPRE (0625173643, faurpro@gmail.com). Num\u00e9ros SIRET : 48389697300052 R\u00e9daction du site Internet Directeur de la publication : Bertrand FAUR Contact : 0625173643 ; cabinetfaur@gmail.com H\u00e9bergeur du site Internet Le site [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales - Bertrand FAUR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales - Bertrand FAUR\" \/>\n<meta property=\"og:description\" content=\"Mentions L\u00e9gales \u00c9dition du site Internet Le site SITE (www.faur.pro), accessible \u00e0 l\u2019adresse URL https:\/\/www.faur.pro est \u00e9dit\u00e9 par Bertrand FAUR , dont le domicile est situ\u00e9 LASSEUBE-PROPRE (0625173643, faurpro@gmail.com). Num\u00e9ros SIRET : 48389697300052 R\u00e9daction du site Internet Directeur de la publication : Bertrand FAUR Contact : 0625173643 ; cabinetfaur@gmail.com H\u00e9bergeur du site Internet Le site [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Bertrand FAUR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-02T14:05:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"MedicalWebPage\"],\"@id\":\"https:\\\/\\\/faur.pro\\\/index.php\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/faur.pro\\\/index.php\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales - Bertrand FAUR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/faur.pro\\\/#website\"},\"datePublished\":\"2019-05-18T15:55:32+00:00\",\"dateModified\":\"2024-06-02T14:05:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/faur.pro\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/faur.pro\\\/index.php\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/faur.pro\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/faur.pro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/faur.pro\\\/#website\",\"url\":\"https:\\\/\\\/faur.pro\\\/\",\"name\":\"Bertrand FAUR\",\"description\":\"Fasciath\u00e9rapie (Fascial Counterstrain\u00a9) &amp; Conseiller Sant\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/faur.pro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales - Bertrand FAUR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales - Bertrand FAUR","og_description":"Mentions L\u00e9gales \u00c9dition du site Internet Le site SITE (www.faur.pro), accessible \u00e0 l\u2019adresse URL https:\/\/www.faur.pro est \u00e9dit\u00e9 par Bertrand FAUR , dont le domicile est situ\u00e9 LASSEUBE-PROPRE (0625173643, faurpro@gmail.com). Num\u00e9ros SIRET : 48389697300052 R\u00e9daction du site Internet Directeur de la publication : Bertrand FAUR Contact : 0625173643 ; cabinetfaur@gmail.com H\u00e9bergeur du site Internet Le site [&hellip;]","og_url":"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/","og_site_name":"Bertrand FAUR","article_modified_time":"2024-06-02T14:05:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","MedicalWebPage"],"@id":"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/","url":"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales - Bertrand FAUR","isPartOf":{"@id":"https:\/\/faur.pro\/#website"},"datePublished":"2019-05-18T15:55:32+00:00","dateModified":"2024-06-02T14:05:20+00:00","breadcrumb":{"@id":"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/faur.pro\/index.php\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/faur.pro\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9 &amp; mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/faur.pro\/#website","url":"https:\/\/faur.pro\/","name":"Bertrand FAUR","description":"Fasciath\u00e9rapie (Fascial Counterstrain\u00a9) &amp; Conseiller Sant\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faur.pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P9rKnb-3","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":2,"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1749,"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/1749"}],"wp:attachment":[{"href":"https:\/\/faur.pro\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}